{"id":16714,"date":"2025-07-15T05:43:26","date_gmt":"2025-07-15T11:43:26","guid":{"rendered":"https:\/\/nicaseeker.com\/directory\/\/garcia-and-bodan-san-juan-sjds\/"},"modified":"2026-07-11T20:45:01","modified_gmt":"2026-07-12T02:45:01","slug":"garcia-and-bodan-san-juan-sjds","status":"publish","type":"at_biz_dir","link":"https:\/\/nicaseeker.com\/es\/directory\/services\/garcia-and-bodan-san-juan-sjds\/","title":{"rendered":"Garc\u00eda y Bodan San Juan del Sur"},"content":{"rendered":"<p data-start=\"1391\" data-end=\"1694\"><strong data-start=\"1391\" data-end=\"1428\">Garcia and Bodan San Juan Del Sur<\/strong> es un despacho jur\u00eddico respetado que ofrece servicios profesionales tanto a clientes nacionales como internacionales. Situada a dos manzanas al norte del Restaurante El Tim\u00f3n, junto al Hotel Alc\u00e1zar, la oficina ofrece un acceso conveniente para cualquiera que busque apoyo legal en el sur de Nicaragua.<\/p>\n<p data-start=\"1696\" data-end=\"2025\">Con una fuerte presencia en derecho inmobiliario, empresarial y corporativo, <strong data-start=\"1764\" data-end=\"1784\">Garc\u00eda y Bodan<\/strong> se ha forjado una reputaci\u00f3n por gestionar transacciones complejas y guiar a sus clientes a trav\u00e9s de procesos regulatorios. Su equipo legal trabaja con promotores inmobiliarios, emprendedores y clientes particulares, garantizando el cumplimiento legal y la seguridad contractual.<\/p>\n<p data-start=\"2027\" data-end=\"2235\">Conocida por su comunicaci\u00f3n clara, atenci\u00f3n al detalle y altos est\u00e1ndares profesionales, <strong data-start=\"2112\" data-end=\"2149\">Garcia y Bodan San Juan Del Sur<\/strong> es el bufete de referencia para una experiencia legal fiable y basada en la localidad en la regi\u00f3n de Rivas.<\/p>\n","protected":false},"author":14,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[5632],"at_biz_dir-category":[7272,7469,6331,6161,6327,7273,7116],"at_biz_dir-location":[5764],"at_biz_dir-tags":[7472,7470,7473,7471,7475],"class_list":["post-16714","at_biz_dir","type-at_biz_dir","status-publish","has-post-thumbnail","hentry","atbdp_listing_types-directorio-de-negocios","at_biz_dir-category-abogados","at_biz_dir-category-ayuda-con-contabilidad-impuestos","at_biz_dir-category-consultants","at_biz_dir-category-professional-services","at_biz_dir-category-servicios-de-expatriacion-reubicacion","at_biz_dir-category-servicios-inmobiliarios","at_biz_dir-category-servicios-legales","at_biz_dir-location-san-juan-del-sur","at_biz_dir-tags-abogados","at_biz_dir-tags-derecho-corporativo","at_biz_dir-tags-derecho-inmobiliario","at_biz_dir-tags-despacho-de-abogados","at_biz_dir-tags-servicios-juridicos-rivas"],"_links":{"self":[{"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir\/16714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/comments?post=16714"}],"version-history":[{"count":1,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir\/16714\/revisions"}],"predecessor-version":[{"id":17254,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir\/16714\/revisions\/17254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/media\/5643"}],"wp:attachment":[{"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/media?parent=16714"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/atbdp_listing_types?post=16714"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir-category?post=16714"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir-location?post=16714"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/nicaseeker.com\/es\/wp-json\/wp\/v2\/at_biz_dir-tags?post=16714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}